{"id":38354,"date":"2023-11-15T18:52:12","date_gmt":"2023-11-15T18:52:12","guid":{"rendered":"https:\/\/termotom.com\/protiprasni-trak-brez-perforacije-za-debelino-plosc-16-do-25-mm\/"},"modified":"2026-04-01T12:05:37","modified_gmt":"2026-04-01T12:05:37","slug":"staubstreifen-ohne-perforation-fuer-plattenstaerken-von-16-bis-25-mm","status":"publish","type":"product","link":"https:\/\/termotom.com\/de\/staubstreifen-ohne-perforation-fuer-plattenstaerken-von-16-bis-25-mm\/","title":{"rendered":"Staubstreifen ohne Perforation f\u00fcr Plattenst\u00e4rken von 16 bis 25 mm"},"content":{"rendered":"<p>Staubband ohne Perforation zur Zellabdichtung in mehrschichtigen Polycarbonatplatten. Kleben Sie das Band \u00fcber die offenen Zellen. Dadurch wird das Eindringen von Schmutz in die Zellen verhindert. Das Staubband allein ist nicht ausreichend. Wir empfehlen, die Platten anschlie\u00dfend mit einem Kodierprofil zu versehen. Kleben Sie das Klebeband ohne Perforation auf die Oberseite, da so das Kondenswasser nicht abflie\u00dfen kann.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Staubband ohne Perforation zum Verschlie\u00dfen von mehrschichtigen Polycarbonatplatten. 33 m Band pro Spule.<\/p>\n","protected":false},"featured_media":38339,"comment_status":"open","ping_status":"closed","template":"","meta":{"_acf_changed":false},"product_brand":[],"product_cat":[1799,1935],"product_tag":[],"class_list":["post-38354","product","type-product","status-publish","has-post-thumbnail","product_cat-befestigungsmaterialien-fuer-bedachungen","product_cat-gurte-und-dichtungen","pa_debelina-16-25mm","pa_dolzina-10-m","pa_dolzina-33-m","first","instock","taxable","shipping-taxable","purchasable","product-type-simple"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Staubstreifen ohne Perforation f\u00fcr Plattenst\u00e4rken von 16 bis 25 mm - Trgovina Termotom<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/termotom.com\/de\/staubstreifen-ohne-perforation-fuer-plattenstaerken-von-16-bis-25-mm\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Staubstreifen ohne Perforation f\u00fcr Plattenst\u00e4rken von 16 bis 25 mm - Trgovina Termotom\" \/>\n<meta property=\"og:description\" content=\"Staubband ohne Perforation zum Verschlie\u00dfen von mehrschichtigen Polycarbonatplatten. 33 m Band pro Spule.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/termotom.com\/de\/staubstreifen-ohne-perforation-fuer-plattenstaerken-von-16-bis-25-mm\/\" \/>\n<meta property=\"og:site_name\" content=\"Trgovina Termotom\" \/>\n<meta property=\"article:modified_time\" content=\"2026-04-01T12:05:37+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/termotom.com\/wp-content\/uploads\/XC-2981_barvna-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"2111\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/termotom.com\/de\/staubstreifen-ohne-perforation-fuer-plattenstaerken-von-16-bis-25-mm\/\",\"url\":\"https:\/\/termotom.com\/de\/staubstreifen-ohne-perforation-fuer-plattenstaerken-von-16-bis-25-mm\/\",\"name\":\"Staubstreifen ohne Perforation f\u00fcr Plattenst\u00e4rken von 16 bis 25 mm - Trgovina Termotom\",\"isPartOf\":{\"@id\":\"https:\/\/termotom.com\/de\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/termotom.com\/de\/staubstreifen-ohne-perforation-fuer-plattenstaerken-von-16-bis-25-mm\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/termotom.com\/de\/staubstreifen-ohne-perforation-fuer-plattenstaerken-von-16-bis-25-mm\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/termotom.com\/wp-content\/uploads\/XC-2981_barvna-scaled.jpg\",\"datePublished\":\"2023-11-15T18:52:12+00:00\",\"dateModified\":\"2026-04-01T12:05:37+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/termotom.com\/de\/staubstreifen-ohne-perforation-fuer-plattenstaerken-von-16-bis-25-mm\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/termotom.com\/de\/staubstreifen-ohne-perforation-fuer-plattenstaerken-von-16-bis-25-mm\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/termotom.com\/de\/staubstreifen-ohne-perforation-fuer-plattenstaerken-von-16-bis-25-mm\/#primaryimage\",\"url\":\"https:\/\/termotom.com\/wp-content\/uploads\/XC-2981_barvna-scaled.jpg\",\"contentUrl\":\"https:\/\/termotom.com\/wp-content\/uploads\/XC-2981_barvna-scaled.jpg\",\"width\":2560,\"height\":2111},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/termotom.com\/de\/staubstreifen-ohne-perforation-fuer-plattenstaerken-von-16-bis-25-mm\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/termotom.com\/de\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\/\/termotom.com\/de\/shop\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Staubstreifen ohne Perforation f\u00fcr Plattenst\u00e4rken von 16 bis 25 mm\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/termotom.com\/de\/#website\",\"url\":\"https:\/\/termotom.com\/de\/\",\"name\":\"Trgovina Termotom\",\"description\":\"Spletna trgovina\",\"publisher\":{\"@id\":\"https:\/\/termotom.com\/de\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/termotom.com\/de\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/termotom.com\/de\/#organization\",\"name\":\"Trgovina Termotom\",\"url\":\"https:\/\/termotom.com\/de\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/termotom.com\/de\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/termotom.com\/wp-content\/uploads\/logo.png\",\"contentUrl\":\"https:\/\/termotom.com\/wp-content\/uploads\/logo.png\",\"width\":400,\"height\":60,\"caption\":\"Trgovina Termotom\"},\"image\":{\"@id\":\"https:\/\/termotom.com\/de\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Staubstreifen ohne Perforation f\u00fcr Plattenst\u00e4rken von 16 bis 25 mm - Trgovina Termotom","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/termotom.com\/de\/staubstreifen-ohne-perforation-fuer-plattenstaerken-von-16-bis-25-mm\/","og_locale":"de_DE","og_type":"article","og_title":"Staubstreifen ohne Perforation f\u00fcr Plattenst\u00e4rken von 16 bis 25 mm - Trgovina Termotom","og_description":"Staubband ohne Perforation zum Verschlie\u00dfen von mehrschichtigen Polycarbonatplatten. 33 m Band pro Spule.","og_url":"https:\/\/termotom.com\/de\/staubstreifen-ohne-perforation-fuer-plattenstaerken-von-16-bis-25-mm\/","og_site_name":"Trgovina Termotom","article_modified_time":"2026-04-01T12:05:37+00:00","og_image":[{"width":2560,"height":2111,"url":"https:\/\/termotom.com\/wp-content\/uploads\/XC-2981_barvna-scaled.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/termotom.com\/de\/staubstreifen-ohne-perforation-fuer-plattenstaerken-von-16-bis-25-mm\/","url":"https:\/\/termotom.com\/de\/staubstreifen-ohne-perforation-fuer-plattenstaerken-von-16-bis-25-mm\/","name":"Staubstreifen ohne Perforation f\u00fcr Plattenst\u00e4rken von 16 bis 25 mm - Trgovina Termotom","isPartOf":{"@id":"https:\/\/termotom.com\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/termotom.com\/de\/staubstreifen-ohne-perforation-fuer-plattenstaerken-von-16-bis-25-mm\/#primaryimage"},"image":{"@id":"https:\/\/termotom.com\/de\/staubstreifen-ohne-perforation-fuer-plattenstaerken-von-16-bis-25-mm\/#primaryimage"},"thumbnailUrl":"https:\/\/termotom.com\/wp-content\/uploads\/XC-2981_barvna-scaled.jpg","datePublished":"2023-11-15T18:52:12+00:00","dateModified":"2026-04-01T12:05:37+00:00","breadcrumb":{"@id":"https:\/\/termotom.com\/de\/staubstreifen-ohne-perforation-fuer-plattenstaerken-von-16-bis-25-mm\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/termotom.com\/de\/staubstreifen-ohne-perforation-fuer-plattenstaerken-von-16-bis-25-mm\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/termotom.com\/de\/staubstreifen-ohne-perforation-fuer-plattenstaerken-von-16-bis-25-mm\/#primaryimage","url":"https:\/\/termotom.com\/wp-content\/uploads\/XC-2981_barvna-scaled.jpg","contentUrl":"https:\/\/termotom.com\/wp-content\/uploads\/XC-2981_barvna-scaled.jpg","width":2560,"height":2111},{"@type":"BreadcrumbList","@id":"https:\/\/termotom.com\/de\/staubstreifen-ohne-perforation-fuer-plattenstaerken-von-16-bis-25-mm\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/termotom.com\/de\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/termotom.com\/de\/shop\/"},{"@type":"ListItem","position":3,"name":"Staubstreifen ohne Perforation f\u00fcr Plattenst\u00e4rken von 16 bis 25 mm"}]},{"@type":"WebSite","@id":"https:\/\/termotom.com\/de\/#website","url":"https:\/\/termotom.com\/de\/","name":"Trgovina Termotom","description":"Spletna trgovina","publisher":{"@id":"https:\/\/termotom.com\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/termotom.com\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/termotom.com\/de\/#organization","name":"Trgovina Termotom","url":"https:\/\/termotom.com\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/termotom.com\/de\/#\/schema\/logo\/image\/","url":"https:\/\/termotom.com\/wp-content\/uploads\/logo.png","contentUrl":"https:\/\/termotom.com\/wp-content\/uploads\/logo.png","width":400,"height":60,"caption":"Trgovina Termotom"},"image":{"@id":"https:\/\/termotom.com\/de\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/termotom.com\/de\/wp-json\/wp\/v2\/product\/38354","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/termotom.com\/de\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/termotom.com\/de\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/termotom.com\/de\/wp-json\/wp\/v2\/comments?post=38354"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/termotom.com\/de\/wp-json\/wp\/v2\/media\/38339"}],"wp:attachment":[{"href":"https:\/\/termotom.com\/de\/wp-json\/wp\/v2\/media?parent=38354"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/termotom.com\/de\/wp-json\/wp\/v2\/product_brand?post=38354"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/termotom.com\/de\/wp-json\/wp\/v2\/product_cat?post=38354"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/termotom.com\/de\/wp-json\/wp\/v2\/product_tag?post=38354"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}